{"id":1,"count":78,"description":"Design \/ Inspiration","link":"https:\/\/aceinfowayindia.com\/blog\/category\/design-inspiration\/","name":"Design \/ Inspiration","slug":"design-inspiration","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/aceinfowayindia.com\/blog\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aceinfowayindia.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/aceinfowayindia.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/aceinfowayindia.com\/blog\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}